{"id":405,"count":3,"description":"","link":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/","name":"pistols","slug":"pistols","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pistols Archives - Lucky Gunner Lounge<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pistols Archives - Lucky Gunner Lounge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucky Gunner Lounge\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.luckygunner.com\/lounge\/media\/luckygunner.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/tag\\\/pistols\\\/\",\"url\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/tag\\\/pistols\\\/\",\"name\":\"pistols Archives - Lucky Gunner Lounge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/tag\\\/pistols\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/tag\\\/pistols\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pistols\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/#website\",\"url\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/\",\"name\":\"Lucky Gunner Lounge\",\"description\":\"Reliable shooting advice for regular people.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.luckygunner.com\\\/lounge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pistols Archives - Lucky Gunner Lounge","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"pistols Archives - Lucky Gunner Lounge","og_url":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/","og_site_name":"Lucky Gunner Lounge","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.luckygunner.com\/lounge\/media\/luckygunner.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/","url":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/","name":"pistols Archives - Lucky Gunner Lounge","isPartOf":{"@id":"https:\/\/www.luckygunner.com\/lounge\/#website"},"breadcrumb":{"@id":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.luckygunner.com\/lounge\/tag\/pistols\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.luckygunner.com\/lounge\/"},{"@type":"ListItem","position":2,"name":"pistols"}]},{"@type":"WebSite","@id":"https:\/\/www.luckygunner.com\/lounge\/#website","url":"https:\/\/www.luckygunner.com\/lounge\/","name":"Lucky Gunner Lounge","description":"Reliable shooting advice for regular people.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.luckygunner.com\/lounge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.luckygunner.com\/lounge\/wp-json\/wp\/v2\/tags\/405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luckygunner.com\/lounge\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.luckygunner.com\/lounge\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.luckygunner.com\/lounge\/wp-json\/wp\/v2\/posts?tags=405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}